{"id":2716,"date":"2016-03-22T09:57:15","date_gmt":"2016-03-22T08:57:15","guid":{"rendered":"http:\/\/www.admiraal.com\/en\/producten\/bifolia\/"},"modified":"2022-04-25T12:24:44","modified_gmt":"2022-04-25T10:24:44","slug":"scilla-bifolia","status":"publish","type":"al_product","link":"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/","title":{"rendered":"Scilla bifolia"},"content":{"rendered":"<p><strong>Scilla bifolia<\/strong><\/p>\n<p>Scilla bifolia: Blooms in spring, around March and grows to a height of about 10 cm. The small flowers are blue in color.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Scilla bifolia<\/strong><\/p>\n<p>Scilla bifolia: Blooms in spring, around March and grows to a height of about 10 cm. The small flowers are blue in color.<\/p>\n","protected":false},"featured_media":13355,"template":"","meta":[],"al_product-cat":[181,201],"class_list":["post-2716","al_product","type-al_product","status-publish","has-post-thumbnail","hentry","al_product-cat-najaars-catalogus-en","al_product-cat-scilla-en","variable-product"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Scilla bifolia - Admiraal.com<\/title>\n<meta name=\"description\" content=\"Scilla bifolia: Blooms in spring, around March and grows to a height of about 10 cm. The small flowers are blue in color.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scilla bifolia - Admiraal.com\" \/>\n<meta property=\"og:description\" content=\"Scilla bifolia: Blooms in spring, around March and grows to a height of about 10 cm. The small flowers are blue in color.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/\" \/>\n<meta property=\"og:site_name\" content=\"Admiraal.com\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-25T10:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.admiraal.com\/wp-content\/uploads\/2016\/03\/Scilla-bifolia-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"342\" \/>\n\t<meta property=\"og:image:height\" content=\"349\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Scilla bifolia - Admiraal.com","description":"Scilla bifolia: Blooms in spring, around March and grows to a height of about 10 cm. The small flowers are blue in color.","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Scilla bifolia - Admiraal.com","og_description":"Scilla bifolia: Blooms in spring, around March and grows to a height of about 10 cm. The small flowers are blue in color.","og_url":"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/","og_site_name":"Admiraal.com","article_modified_time":"2022-04-25T10:24:44+00:00","og_image":[{"width":342,"height":349,"url":"https:\/\/www.admiraal.com\/wp-content\/uploads\/2016\/03\/Scilla-bifolia-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/","url":"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/","name":"Scilla bifolia - Admiraal.com","isPartOf":{"@id":"https:\/\/www.admiraal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/#primaryimage"},"image":{"@id":"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.admiraal.com\/wp-content\/uploads\/2016\/03\/Scilla-bifolia-5.jpg","datePublished":"2016-03-22T08:57:15+00:00","dateModified":"2022-04-25T10:24:44+00:00","description":"Scilla bifolia: Blooms in spring, around March and grows to a height of about 10 cm. The small flowers are blue in color.","breadcrumb":{"@id":"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/#primaryimage","url":"https:\/\/www.admiraal.com\/wp-content\/uploads\/2016\/03\/Scilla-bifolia-5.jpg","contentUrl":"https:\/\/www.admiraal.com\/wp-content\/uploads\/2016\/03\/Scilla-bifolia-5.jpg","width":342,"height":349},{"@type":"BreadcrumbList","@id":"https:\/\/www.admiraal.com\/en\/producten\/scilla-bifolia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.admiraal.com\/en\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/www.admiraal.com\/producten\/"},{"@type":"ListItem","position":3,"name":"Scilla bifolia"}]},{"@type":"WebSite","@id":"https:\/\/www.admiraal.com\/#website","url":"https:\/\/www.admiraal.com\/","name":"Admiraal.com","description":"","publisher":{"@id":"https:\/\/www.admiraal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.admiraal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.admiraal.com\/#organization","name":"admiraal.com","url":"https:\/\/www.admiraal.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.admiraal.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.admiraal.com\/wp-content\/uploads\/2017\/02\/admiraal-logo-rob-2017.jpg","contentUrl":"https:\/\/www.admiraal.com\/wp-content\/uploads\/2017\/02\/admiraal-logo-rob-2017.jpg","width":3207,"height":888,"caption":"admiraal.com"},"image":{"@id":"https:\/\/www.admiraal.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.admiraal.com\/en\/wp-json\/wp\/v2\/al_product\/2716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.admiraal.com\/en\/wp-json\/wp\/v2\/al_product"}],"about":[{"href":"https:\/\/www.admiraal.com\/en\/wp-json\/wp\/v2\/types\/al_product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.admiraal.com\/en\/wp-json\/wp\/v2\/media\/13355"}],"wp:attachment":[{"href":"https:\/\/www.admiraal.com\/en\/wp-json\/wp\/v2\/media?parent=2716"}],"wp:term":[{"taxonomy":"al_product-cat","embeddable":true,"href":"https:\/\/www.admiraal.com\/en\/wp-json\/wp\/v2\/al_product-cat?post=2716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}